{"id":6693,"date":"2022-03-15T10:00:00","date_gmt":"2022-03-15T13:00:00","guid":{"rendered":"https:\/\/cervejaemalte.com.br\/?p=6693"},"modified":"2023-06-09T08:14:10","modified_gmt":"2023-06-09T11:14:10","slug":"marcas-de-cerveja","status":"publish","type":"post","link":"https:\/\/cervejaemalte.com.br\/es\/blog\/marcas-de-cerveza\/","title":{"rendered":"<strong>Las marcas de cerveza m\u00e1s valiosas del mundo\u00a0<\/strong>\u00a0"},"content":{"rendered":"<p>Tras unos a\u00f1os dif\u00edciles, en los que las marcas de cerveza de todo el mundo han intentado adaptarse a los importantes cambios en el estilo de vida provocados por la pandemia, las principales marcas de cerveza han registrado<strong> p\u00e9rdida de 16% de su valor de marca acumulado<\/strong> en comparaci\u00f3n con el inicio de la crisis, seg\u00fan Brand Finance.<\/p>\n\n\n\n<p>Ahora, m\u00e1s que nunca, los gigantes de la industria cervecera compiten metro a metro por el espacio publicitario, las estanter\u00edas de los supermercados y, por supuesto, las ventas de los consumidores.<\/p>\n\n\n\n<p>Sin embargo, incluso en la crisis, siempre hay quien gana la carrera por el oro.&nbsp;<\/p>\n\n\n\n<p><strong>\u00bfTiene curiosidad por saber qu\u00e9 marca de cerveza es actualmente la m\u00e1s valiosa del mundo?<\/strong><\/p>\n\n\n\n<p>El \u00faltimo informe sobre marcas de cerveza, vino y licores de<a href=\"https:\/\/brandirectory.com\/rankings\/beers\/\"> Marca Finanzas<\/a>una consultora brit\u00e1nica de valoraci\u00f3n y estrategia empresarial, ha cotizado en bolsa <strong>las marcas de cerveza con mayor valor comercial del mundo en el \u00faltimo a\u00f1o <\/strong>y lo compartiremos contigo ahora.<\/p>\n\n\n\n<p>Descubra cu\u00e1les son las 5 mejores de este ranking y qu\u00e9 puede esperar de estas cervezas en el paladar.<\/p>\n\n\n\n<h2 class=\"has-luminous-vivid-orange-color has-text-color wp-block-heading\" id=\"1-corona\"><strong>1. Corona<\/strong><\/h2>\n\n\n\n<p>Iron\u00eda del destino o no, la cerveza que lleva el nombre del virus que sembr\u00f3 el caos por todo el planeta es actualmente la marca de cerveza m\u00e1s valiosa del mundo.&nbsp;<\/p>\n\n\n\n<p>Nacida en M\u00e9xico, esta cerveza tipo Pilsen fue producida por primera vez en 1925 por la Cervecer\u00eda Modelo, situada en Ciudad de M\u00e9xico.&nbsp;<\/p>\n\n\n\n<p>Hoy forma parte de la familia Anheuser-Bush InBev y se vende en m\u00e1s de 150 pa\u00edses.<\/p>\n\n\n\n<p>Corona est\u00e1 valorada actualmente en $5.800 millones de d\u00f3lares.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"ingredientes\"><em><strong>Ingredientes:<\/strong><\/em><\/h3>\n\n\n\n<p>Corona Extra, la marca insignia de Corona, se elabora con agua, malta, arroz y l\u00fapulo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"caracteristicas-sensoriais\"><strong><em>Caracter\u00edsticas sensoriales:<\/em><\/strong><\/h3>\n\n\n\n<p>La cerveza es ic\u00f3nica por su sabor -con una rodaja de lim\u00f3n en el cuello para reforzar la acidez de sus dosis c\u00edtricas- y tiene un sabor ligero y refrescante con escaso amargor del l\u00fapulo. Tiene una graduaci\u00f3n alcoh\u00f3lica de 4,6%.<\/p>\n\n\n\n<h2 class=\"has-luminous-vivid-orange-color has-text-color wp-block-heading\" id=\"2-heineken\"><strong>2. Heineken&nbsp;<\/strong><\/h2>\n\n\n\n<p>La segunda marca de cerveza m\u00e1s valiosa del mundo es holandesa.<\/p>\n\n\n\n<p>Valorada en $5.600 millones de d\u00f3lares, la historia de Heineken comenz\u00f3 en 1864, cuando Gerard Adriaan Heineken adquiri\u00f3 una peque\u00f1a f\u00e1brica de cerveza en \u00c1msterdam, en el coraz\u00f3n de los Pa\u00edses Bajos.&nbsp;<\/p>\n\n\n\n<p>Cinco a\u00f1os m\u00e1s tarde, en 1869, Gerard decidi\u00f3 cambiar el proceso de elaboraci\u00f3n de la cerveza, adoptando el m\u00e9todo alem\u00e1n de fermentaci\u00f3n baja.&nbsp;<\/p>\n\n\n\n<p>Seg\u00fan la cervecera, se calcula que cada d\u00eda se sirven 25 millones de Heinekens en 192 pa\u00edses.&nbsp;<\/p>\n\n\n\n<p>La receta de la cerveza, dicen, sigue siendo la misma desde hace m\u00e1s de un siglo.&nbsp;<\/p>\n\n\n\n<p>En Brasil, la cartera de cervezas del Grupo Heineken tambi\u00e9n incluye Sol, Kaiser, Bavaria, Amstel, Kirin Ichiban, Schin, No Grau, Devassa, Baden Baden, Eisenbahn y Glacial.<\/p>\n\n\n\n<p>Las cervezas se elaboran en doce cervecer\u00edas y dos microcervecer\u00edas repartidas por todo Brasil.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"ingredientes\"><strong><em>Ingredientes:<\/em><\/strong><\/h3>\n\n\n\n<p>La cerveza lager Heineken s\u00f3lo contiene tres ingredientes principales - cebada, l\u00fapulo y agua - adem\u00e1s de la famosa levadura A.&nbsp;<\/p>\n\n\n\n<p>Seg\u00fan la historia, fue un alumno de Louis Pasteur, el Dr. Elion, quien consigui\u00f3 aislar la cepa de levadura A en un laboratorio de Heineken en 1886. <em>(La gu\u00eda Oxford de la cerveza).<\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"caracteristicas-sensoriais\"><strong><em>Caracter\u00edsticas sensoriales:<\/em><\/strong><\/h3>\n\n\n\n<p>La cerveza pertenece al estilo American Premium Lager y se caracteriza por su amargor m\u00e1s intenso que otras cervezas populares.<\/p>\n\n\n\n<h2 class=\"has-luminous-vivid-orange-color has-text-color wp-block-heading\" id=\"3-budweiser\"><strong>3. Budweiser&nbsp;<\/strong><\/h2>\n\n\n\n<p>En tercer lugar aparece la primera de las marcas de cerveza con mayor valor comercial en Estados Unidos.<\/p>\n\n\n\n<p>Bud, como se la conoce, fue fundada en 1876 por un inmigrante alem\u00e1n, Adolphus Busch.&nbsp;<\/p>\n\n\n\n<p>Hoy Budweiser forma parte del grupo Anheuser-Bush InBev y se vende en m\u00e1s de 85 pa\u00edses, con la misma receta que tiene m\u00e1s de 140 a\u00f1os de historia.<\/p>\n\n\n\n<p>En Brasil, Budweiser se produce en la planta de Jacare\u00ed, en el interior de S\u00e3o Paulo.<\/p>\n\n\n\n<p>El valor de la marca se estima en $4.700 millones de d\u00f3lares.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"ingredientes\"><strong><em>Ingredientes:<\/em><\/strong><\/h3>\n\n\n\n<p>Budweiser se elabora con agua, malta, arroz y l\u00fapulo. Al igual que Heineken, tambi\u00e9n tiene su propia levadura.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"caracteristicas-sensoriais\"><strong><em>Caracter\u00edsticas sensoriales:<\/em><\/strong><\/h3>\n\n\n\n<p>La cerveza Budweiser es una Lager americana de sabor ligero, limpio y ligeramente dulce, con cierto toque afrutado a manzana, color claro y aroma discreto.&nbsp;<\/p>\n\n\n\n<p>Las virutas de haya, la madera especial utilizada en el proceso de fermentaci\u00f3n y maduraci\u00f3n de Budweiser, le confieren un sabor equilibrado, fuerte al principio y suave al final.<\/p>\n\n\n\n<p><a href=\"https:\/\/cursos.cervejaemalte.com.br\/sommelier-de-cervejas\"><strong><em>&gt; Descubra todos los detalles del Curso de Sumiller de Cerveza de la ESCM.<\/em><\/strong><\/a><\/p>\n\n\n\n<h2 class=\"has-luminous-vivid-orange-color has-text-color wp-block-heading\" id=\"4-victoria\"><strong>4. Victoria&nbsp;<\/strong><\/h2>\n\n\n\n<p>Al igual que Corona, la cuarta marca de cerveza m\u00e1s valiosa del mundo es mexicana.<\/p>\n\n\n\n<p>Victoria es una cerveza lager de Viena producida por primera vez en Toluca, M\u00e9xico, en 1865 por la Compa\u00f1\u00eda Toluca y M\u00e9xico.&nbsp;<\/p>\n\n\n\n<p>Grupo Modelo compr\u00f3 Compa\u00f1\u00eda Toluca y M\u00e9xico en 1935, pero s\u00f3lo continu\u00f3 produciendo sus marcas m\u00e1s populares: Pilsner y Victoria. Pilsner dej\u00f3 de producirse en 1943, pero Victoria ha permanecido en el mercado hasta nuestros d\u00edas. Por eso Victoria est\u00e1 considerada la cerveza mexicana m\u00e1s antigua.<\/p>\n\n\n\n<p>Luego, en 2012, fue el turno de Anheuser-Busch InBev, propietaria de AmBev, de comprar Grupo Modelo.<\/p>\n\n\n\n<p>Seg\u00fan la marca, tras la Primera Guerra Mundial el estilo Viena pr\u00e1cticamente desapareci\u00f3 en Europa, pero encontr\u00f3 su nuevo hogar en M\u00e9xico. La cerveza Victoria ha mantenido viva la receta de las maltas caramelizadas y se ha ganado al fiel p\u00fablico mexicano que la llama cari\u00f1osamente por su apodo <em>Viky.<\/em><\/p>\n\n\n\n<p>Seg\u00fan el informe Brand Finance, la marca Victoria tiene un valor de 1.400 millones de d\u00f3lares.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/youtu.be\/Ox5QRHCED4A\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"ingredientes\"><strong><em>Ingredientes:<\/em><\/strong><\/h3>\n\n\n\n<p>Elaborada con agua, malta de cebada, cereales no malteados y l\u00fapulo.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"caracteristicas-sensoriais\"><strong><em>Caracter\u00edsticas sensoriales:<\/em><\/strong><\/h3>\n\n\n\n<p>Victoria es una cerveza de color \u00e1mbar del tipo Vienna Lager, con 4\u00ba de alcohol. Tiene un cuerpo suave, de ligero a medio, con notas de malta tostada, manzana y carambola.<\/p>\n\n\n\n<p><strong><em>&gt;&gt; Lea tambi\u00e9n:<\/em><\/strong><a href=\"https:\/\/cervejaemalte.com.br\/es\/beber-cerveja-faz-bem-a-saude\/\"><strong><em> 5 estudios cient\u00edficos que te dan luz verde para beber cerveza<\/em><\/strong><\/a><\/p>\n\n\n\n<h2 class=\"has-luminous-vivid-orange-color has-text-color wp-block-heading\" id=\"5-bud-light\"><strong>5. Bud Light&nbsp;<\/strong><\/h2>\n\n\n\n<p>La quinta en la clasificaci\u00f3n de las marcas de cerveza m\u00e1s valiosas del mundo es la estadounidense Bud Light, valorada en US$3.900 millones.<\/p>\n\n\n\n<p>Con un bajo contenido de alcohol y s\u00f3lo 110 calor\u00edas, Bud Light es la versi\u00f3n m\u00e1s ligera de Budweiser.<\/p>\n\n\n\n<p>Se cre\u00f3 a principios de los a\u00f1os ochenta, cuando la tradicional cervecera Anheuser-Busch quer\u00eda ampliar la gama de la marca Budweiser.&nbsp;<\/p>\n\n\n\n<p>En abril de 1982, la cervecera lanz\u00f3 al mercado estadounidense Budweiser Light, una versi\u00f3n m\u00e1s d\u00e9bil de la Budweiser tradicional.&nbsp;<\/p>\n\n\n\n<p>Unos a\u00f1os m\u00e1s tarde, la cerveza adopt\u00f3 el nombre abreviado de<em> Bud Light <\/em>y en 2001, con el aumento del consumo de cervezas ligeras, la marca se convirti\u00f3 en la cerveza m\u00e1s consumida en EE.UU., superando incluso a su hermana, la Budweiser original.<\/p>\n\n\n\n<p>&nbsp;Hoy, Bud Light es la cerveza m\u00e1s vendida del mundo. <em>cerveza light<\/em> del mundo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"ingredientes\"><strong><em>Ingredientes:<\/em><\/strong><\/h3>\n\n\n\n<p>Bud Light se elabora con agua, malta, arroz y l\u00fapulo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"caracteristicas-sensoriais\"><strong><em>Caracter\u00edsticas sensoriales:<\/em><\/strong><\/h3>\n\n\n\n<p>Bud Light es una cerveza rubia refrescante de estilo americano con un sabor limpio y crujiente y un final r\u00e1pido. Con 4,2% ABV, es ligera y f\u00e1cil de beber.&nbsp;<\/p>\n\n\n\n<p>Al igual que su hermana mayor, Bud Light tambi\u00e9n recibe virutas de madera de haya durante los procesos de fermentaci\u00f3n y maduraci\u00f3n.<\/p>\n\n\n\n<p>La siguiente en la clasificaci\u00f3n es la marca china <strong>Nieve<\/strong>US$3.400 millones; <strong>Modelo<\/strong>M\u00e9xico, con $3.300 millones de d\u00f3lares; Jap\u00f3n <strong>Kirin<\/strong>US$2.853 millones; <strong>Miller Lite <\/strong>de Estados Unidos, con $2.850 millones de d\u00f3lares; <strong>Asahi<\/strong>, tambi\u00e9n de Jap\u00f3n, con $2.848 millones de d\u00f3lares.<\/p>\n\n\n\n<p>Marcas brasile\u00f1as <strong>Skol <\/strong>y <strong>Brahma <\/strong>ocuparon los puestos 11\u00ba y 16\u00ba, respectivamente.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><em><strong>&gt;&gt; Forma parte del mundo cervecero. <a href=\"https:\/\/cervejaemalte.com.br\/es\/cursos\/\">Descubra los cursos de la Escuela de la Cerveza y la Malta.<\/a><\/strong><\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Tras unos a\u00f1os dif\u00edciles, en los que las marcas de cerveza del mundo han intentado adaptarse a los importantes cambios de estilo de vida provocados por la pandemia, las principales marcas de cerveza han registrado una p\u00e9rdida de 16% en su valor de marca acumulado en comparaci\u00f3n con el inicio de esta crisis, seg\u00fan Brand Finance. Ahora, m\u00e1s de [...]<\/p>","protected":false},"author":1,"featured_media":6706,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,77,396,16,44],"tags":[724,720,719,722,723,721,718,717],"class_list":["post-6693","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cerveja-e-marketing","category-cervejarias","category-destaques","category-escm","category-noticias","tag-bud-light","tag-budweiser","tag-cerveja-victoria","tag-corona","tag-heineken","tag-marcas-de-cerveja-do-mundo","tag-marcas-de-cerveja-mais-valiosas-do-mundo","tag-principais-marcas-de-cervejas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>As marcas mais valiosas de cerveja do mundo\u00a0\u00a0 - Cerveja e Malte<\/title>\n<meta name=\"description\" content=\"As marcas mais valiosas de cerveja do mundo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cervejaemalte.com.br\/es\/blog\/marcas-de-cerveza\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"As marcas mais valiosas de cerveja do mundo\u00a0\u00a0 - Cerveja e Malte\" \/>\n<meta property=\"og:description\" content=\"As marcas mais valiosas de cerveja do mundo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cervejaemalte.com.br\/es\/blog\/marcas-de-cerveza\/\" \/>\n<meta property=\"og:site_name\" content=\"Cerveja e Malte\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-15T13:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-09T11:14:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cervejaemalte.com.br\/wp-content\/uploads\/2022\/01\/beer-with-salted-peanut-on-table-2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1709\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"vwwebmaster\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"vwwebmaster\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cervejaemalte.com.br\/blog\/marcas-de-cerveja\/\",\"url\":\"https:\/\/cervejaemalte.com.br\/blog\/marcas-de-cerveja\/\",\"name\":\"As marcas mais valiosas de cerveja do mundo\u00a0\u00a0 - Cerveja e Malte\",\"isPartOf\":{\"@id\":\"https:\/\/cervejaemalte.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/cervejaemalte.com.br\/blog\/marcas-de-cerveja\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/cervejaemalte.com.br\/blog\/marcas-de-cerveja\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cervejaemalte.com.br\/wp-content\/uploads\/2022\/01\/beer-with-salted-peanut-on-table-2-scaled.jpg\",\"datePublished\":\"2022-03-15T13:00:00+00:00\",\"dateModified\":\"2023-06-09T11:14:10+00:00\",\"author\":{\"@id\":\"https:\/\/cervejaemalte.com.br\/#\/schema\/person\/f1cb569af4c641c9da3a7dc2147a1ab8\"},\"description\":\"As marcas mais valiosas de cerveja do mundo\",\"breadcrumb\":{\"@id\":\"https:\/\/cervejaemalte.com.br\/blog\/marcas-de-cerveja\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cervejaemalte.com.br\/blog\/marcas-de-cerveja\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/cervejaemalte.com.br\/blog\/marcas-de-cerveja\/#primaryimage\",\"url\":\"https:\/\/cervejaemalte.com.br\/wp-content\/uploads\/2022\/01\/beer-with-salted-peanut-on-table-2-scaled.jpg\",\"contentUrl\":\"https:\/\/cervejaemalte.com.br\/wp-content\/uploads\/2022\/01\/beer-with-salted-peanut-on-table-2-scaled.jpg\",\"width\":2560,\"height\":1709},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cervejaemalte.com.br\/blog\/marcas-de-cerveja\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/cervejaemalte.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"As marcas mais valiosas de cerveja do mundo\u00a0\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cervejaemalte.com.br\/#website\",\"url\":\"https:\/\/cervejaemalte.com.br\/\",\"name\":\"Cerveja e Malte\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cervejaemalte.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/cervejaemalte.com.br\/#\/schema\/person\/f1cb569af4c641c9da3a7dc2147a1ab8\",\"name\":\"vwwebmaster\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/cervejaemalte.com.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d5d9325311fe1f45c9d73ca30379f21ef2aa3dfaad2b297a1bb7a49062185564?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d5d9325311fe1f45c9d73ca30379f21ef2aa3dfaad2b297a1bb7a49062185564?s=96&d=mm&r=g\",\"caption\":\"vwwebmaster\"},\"sameAs\":[\"https:\/\/www.cervejaemalte.com.br\/blog2021\"],\"url\":\"https:\/\/cervejaemalte.com.br\/es\/blog\/author\/vwwebmaster\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"As marcas mais valiosas de cerveja do mundo\u00a0\u00a0 - Cerveja e Malte","description":"As marcas mais valiosas de cerveja do mundo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cervejaemalte.com.br\/es\/blog\/marcas-de-cerveza\/","og_locale":"es_ES","og_type":"article","og_title":"As marcas mais valiosas de cerveja do mundo\u00a0\u00a0 - Cerveja e Malte","og_description":"As marcas mais valiosas de cerveja do mundo","og_url":"https:\/\/cervejaemalte.com.br\/es\/blog\/marcas-de-cerveza\/","og_site_name":"Cerveja e Malte","article_published_time":"2022-03-15T13:00:00+00:00","article_modified_time":"2023-06-09T11:14:10+00:00","og_image":[{"width":2560,"height":1709,"url":"https:\/\/cervejaemalte.com.br\/wp-content\/uploads\/2022\/01\/beer-with-salted-peanut-on-table-2-scaled.jpg","type":"image\/jpeg"}],"author":"vwwebmaster","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"vwwebmaster","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cervejaemalte.com.br\/blog\/marcas-de-cerveja\/","url":"https:\/\/cervejaemalte.com.br\/blog\/marcas-de-cerveja\/","name":"As marcas mais valiosas de cerveja do mundo\u00a0\u00a0 - Cerveja e Malte","isPartOf":{"@id":"https:\/\/cervejaemalte.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cervejaemalte.com.br\/blog\/marcas-de-cerveja\/#primaryimage"},"image":{"@id":"https:\/\/cervejaemalte.com.br\/blog\/marcas-de-cerveja\/#primaryimage"},"thumbnailUrl":"https:\/\/cervejaemalte.com.br\/wp-content\/uploads\/2022\/01\/beer-with-salted-peanut-on-table-2-scaled.jpg","datePublished":"2022-03-15T13:00:00+00:00","dateModified":"2023-06-09T11:14:10+00:00","author":{"@id":"https:\/\/cervejaemalte.com.br\/#\/schema\/person\/f1cb569af4c641c9da3a7dc2147a1ab8"},"description":"As marcas mais valiosas de cerveja do mundo","breadcrumb":{"@id":"https:\/\/cervejaemalte.com.br\/blog\/marcas-de-cerveja\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cervejaemalte.com.br\/blog\/marcas-de-cerveja\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cervejaemalte.com.br\/blog\/marcas-de-cerveja\/#primaryimage","url":"https:\/\/cervejaemalte.com.br\/wp-content\/uploads\/2022\/01\/beer-with-salted-peanut-on-table-2-scaled.jpg","contentUrl":"https:\/\/cervejaemalte.com.br\/wp-content\/uploads\/2022\/01\/beer-with-salted-peanut-on-table-2-scaled.jpg","width":2560,"height":1709},{"@type":"BreadcrumbList","@id":"https:\/\/cervejaemalte.com.br\/blog\/marcas-de-cerveja\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/cervejaemalte.com.br\/"},{"@type":"ListItem","position":2,"name":"As marcas mais valiosas de cerveja do mundo\u00a0\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/cervejaemalte.com.br\/#website","url":"https:\/\/cervejaemalte.com.br\/","name":"Cerveja e Malte","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cervejaemalte.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/cervejaemalte.com.br\/#\/schema\/person\/f1cb569af4c641c9da3a7dc2147a1ab8","name":"vwwebmaster","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cervejaemalte.com.br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d5d9325311fe1f45c9d73ca30379f21ef2aa3dfaad2b297a1bb7a49062185564?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d5d9325311fe1f45c9d73ca30379f21ef2aa3dfaad2b297a1bb7a49062185564?s=96&d=mm&r=g","caption":"vwwebmaster"},"sameAs":["https:\/\/www.cervejaemalte.com.br\/blog2021"],"url":"https:\/\/cervejaemalte.com.br\/es\/blog\/author\/vwwebmaster\/"}]}},"_links":{"self":[{"href":"https:\/\/cervejaemalte.com.br\/es\/wp-json\/wp\/v2\/posts\/6693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cervejaemalte.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cervejaemalte.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cervejaemalte.com.br\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cervejaemalte.com.br\/es\/wp-json\/wp\/v2\/comments?post=6693"}],"version-history":[{"count":5,"href":"https:\/\/cervejaemalte.com.br\/es\/wp-json\/wp\/v2\/posts\/6693\/revisions"}],"predecessor-version":[{"id":10580,"href":"https:\/\/cervejaemalte.com.br\/es\/wp-json\/wp\/v2\/posts\/6693\/revisions\/10580"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cervejaemalte.com.br\/es\/wp-json\/wp\/v2\/media\/6706"}],"wp:attachment":[{"href":"https:\/\/cervejaemalte.com.br\/es\/wp-json\/wp\/v2\/media?parent=6693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cervejaemalte.com.br\/es\/wp-json\/wp\/v2\/categories?post=6693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cervejaemalte.com.br\/es\/wp-json\/wp\/v2\/tags?post=6693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}